{"id":2609,"date":"2018-08-12T22:36:15","date_gmt":"2018-08-12T20:36:15","guid":{"rendered":"https:\/\/www.semeurdetoiles.fr\/?post_type=project&#038;p=2609"},"modified":"2024-11-01T17:37:03","modified_gmt":"2024-11-01T16:37:03","slug":"chenille-sculpture","status":"publish","type":"project","link":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/","title":{"rendered":"CHENILLE<br><span>Sculpture<\/span>"},"content":{"rendered":"<p>Created in cooperation with the designer Vincent Darr\u00e9, insects are funny and original sculptures. They come from the meeting between Vincent Darr\u00e9\u2019s dadaist world and Semeur d\u2019\u00e9toiles\u2019 poetic world. The caterpillar is articulated and lights. She climbs your cushions and bends into your space. They are already well received (read <strong><a href=\"https:\/\/www.semeurdetoiles.fr\/en\/press\/\">press review<\/a><\/strong>).<\/p>\n<p><strong>Materials<\/strong><\/p>\n<p>Mouth blown glass, brass, LEDs<\/p>\n<p><strong>Dimensions<\/strong><\/p>\n<p>See photos caption<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Created in cooperation with the designer Vincent Darr\u00e9, insects are funny and original sculptures. They come from the meeting between Vincent Darr\u00e9\u2019s dadaist world and Semeur d\u2019\u00e9toiles\u2019 poetic world. The caterpillar is articulated and lights. She climbs your cushions and bends into your space. They are already well received (read press review). Materials Mouth blown [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3627,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"project_category":[74],"project_tag":[],"class_list":["post-2609","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-animals"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHENILLE Lighting Sculpture - Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHENILLE Lighting Sculpture - Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses\" \/>\n<meta property=\"og:description\" content=\"Created in cooperation with the designer Vincent Darr\u00e9, insects are funny and original sculptures. They come from the meeting between Vincent Darr\u00e9\u2019s dadaist world and Semeur d\u2019\u00e9toiles\u2019 poetic world. The caterpillar is articulated and lights. She climbs your cushions and bends into your space. They are already well received (read press review). Materials Mouth blown [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses - Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-01T16:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2020\/03\/vignette_chenille.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/\",\"url\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/\",\"name\":\"CHENILLE Lighting Sculpture - Semeur d'Etoiles - Cr\u00e9ation lumineuses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/vignette_chenille.jpg\",\"datePublished\":\"2018-08-12T20:36:15+00:00\",\"dateModified\":\"2024-11-01T16:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/vignette_chenille.jpg\",\"contentUrl\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/vignette_chenille.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/animals\\\/chenille-sculpture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/creation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHENILLESculpture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/\",\"name\":\"Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses - Paris\",\"description\":\"Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses - Paris\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/#organization\",\"name\":\"Semeur d'\u00c9toiles\",\"url\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo.png\",\"width\":\"400\",\"height\":\"82\",\"caption\":\"Semeur d'\u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/www.semeurdetoiles.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/semeurdetoiles\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ludovic-cl\u00e9ment-d-armont-076b3352\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHENILLE Lighting Sculpture - Semeur d'Etoiles - Cr\u00e9ation lumineuses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/","og_locale":"en_US","og_type":"article","og_title":"CHENILLE Lighting Sculpture - Semeur d'Etoiles - Cr\u00e9ation lumineuses","og_description":"Created in cooperation with the designer Vincent Darr\u00e9, insects are funny and original sculptures. They come from the meeting between Vincent Darr\u00e9\u2019s dadaist world and Semeur d\u2019\u00e9toiles\u2019 poetic world. The caterpillar is articulated and lights. She climbs your cushions and bends into your space. They are already well received (read press review). Materials Mouth blown [&hellip;]","og_site_name":"Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses - Paris","article_modified_time":"2024-11-01T16:37:03+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2020\/03\/vignette_chenille.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/","url":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/","name":"CHENILLE Lighting Sculpture - Semeur d'Etoiles - Cr\u00e9ation lumineuses","isPartOf":{"@id":"https:\/\/www.semeurdetoiles.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/#primaryimage"},"image":{"@id":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/#primaryimage"},"thumbnailUrl":"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2020\/03\/vignette_chenille.jpg","datePublished":"2018-08-12T20:36:15+00:00","dateModified":"2024-11-01T16:37:03+00:00","breadcrumb":{"@id":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/#primaryimage","url":"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2020\/03\/vignette_chenille.jpg","contentUrl":"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2020\/03\/vignette_chenille.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/animals\/chenille-sculpture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.semeurdetoiles.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/www.semeurdetoiles.fr\/en\/creation\/"},{"@type":"ListItem","position":3,"name":"CHENILLESculpture"}]},{"@type":"WebSite","@id":"https:\/\/www.semeurdetoiles.fr\/en\/#website","url":"https:\/\/www.semeurdetoiles.fr\/en\/","name":"Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses - Paris","description":"Semeur d&#039;Etoiles - Cr\u00e9ation lumineuses - Paris","publisher":{"@id":"https:\/\/www.semeurdetoiles.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.semeurdetoiles.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.semeurdetoiles.fr\/en\/#organization","name":"Semeur d'\u00c9toiles","url":"https:\/\/www.semeurdetoiles.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.semeurdetoiles.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2018\/04\/logo.png","contentUrl":"https:\/\/www.semeurdetoiles.fr\/wp-content\/uploads\/2018\/04\/logo.png","width":"400","height":"82","caption":"Semeur d'\u00c9toiles"},"image":{"@id":"https:\/\/www.semeurdetoiles.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/semeurdetoiles\/","https:\/\/www.linkedin.com\/in\/ludovic-cl\u00e9ment-d-armont-076b3352\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/project\/2609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/comments?post=2609"}],"version-history":[{"count":1,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/project\/2609\/revisions"}],"predecessor-version":[{"id":243828,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/project\/2609\/revisions\/243828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/media\/3627"}],"wp:attachment":[{"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/media?parent=2609"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/project_category?post=2609"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.semeurdetoiles.fr\/en\/wp-json\/wp\/v2\/project_tag?post=2609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}